{"id":7754,"date":"2021-03-18T10:56:41","date_gmt":"2021-03-18T10:56:41","guid":{"rendered":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/?p=7754"},"modified":"2021-03-18T10:56:41","modified_gmt":"2021-03-18T10:56:41","slug":"finally-back-welcome-to-mallorca","status":"publish","type":"post","link":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/","title":{"rendered":"Finally back: Welcome to Mallorca"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7757\" src=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg\" alt=\"\" width=\"750\" height=\"531\" srcset=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg 750w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1-311x220.jpg 311w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1-588x416.jpg 588w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1-90x63.jpg 90w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>Your personal dream property in Mallorca is waiting for you<\/h2>\n<p>Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures (7-days only 19.4, update on 17.3).<!--more--><\/p>\n<p>The airlines reacted immediately and significantly increased the number of flights to Mallorca. Many hotels have also announced that they will be reopening in the run-up to Easter.<\/p>\n<p>We look forward to being able to present your dream property to you in person and provide you with all the useful information you need! Arrange your viewing appointment directly with our sales managers or with our office:<\/p>\n<p><strong>Tel. 0034-971 69 80 76 (10am to 6pm).<\/strong><\/p>\n<p>We would now like to inform you about the current Corona rules on Mallorca (update on 17.3.), so that you can enjoy your stay on our sunny island in the best possible way:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7755\" src=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/bild_750.jpg\" alt=\"\" width=\"750\" height=\"510\" srcset=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/bild_750.jpg 750w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/bild_750-324x220.jpg 324w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/bild_750-612x416.jpg 612w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>General obligation to wear a mask in public<\/li>\n<li>Curfew from 10 p.m. to 6 a.m.<\/li>\n<li>Restaurants and bars open indoors and outdoors until 5pm, afterwards delivery service or self-collection is available<\/li>\n<li>Shops open with quantity restrictions until 8pm<\/li>\n<li>Department stores and shopping centers open Monday to Saturday<\/li>\n<li>Sports activities in groups of up to 10 people<\/li>\n<li>Generally, a distance rule of 2 meters to other persons applies<\/li>\n<li>Meeting in private only max. 4 persons from two households<\/li>\n<li>Grouping in public (e.g. on the beach or for drinking) with restrictions<\/li>\n<li>Hotel room occupancy only from the same household<\/li>\n<\/ul>\n<p>For your own safety, please remember that you must present a negative PCR test, bot older than 72 hours, before entering Spain. Violations of these rules can be severely punished! Please inform yourself daily about the valid rules, e.g. in the Mallorca Zeitung (special regulations possible at Easter!).<\/p>\n<p><strong>We look forward meeting you!<\/strong><\/p>\n<p>Bernd Bremer und Reinulf Aniol<br \/>\nManaging Director<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7756\" src=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/footer_750-1.jpg\" alt=\"\" width=\"750\" height=\"488\" srcset=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/footer_750-1.jpg 750w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/footer_750-1-330x215.jpg 330w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/footer_750-1-639x416.jpg 639w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Your personal dream property in Mallorca is waiting for you Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures (7-days only 19.4, update on 17.3).<\/p>\n","protected":false},"author":2,"featured_media":7757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[443,445,399],"tags":[],"class_list":["post-7754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buy_real_estate","category-mallorca-real-estate","category-real_estate_market_mallorca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finally back: Welcome to Mallorca - Immobilien Mallorca Blog<\/title>\n<meta name=\"description\" content=\"Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finally back: Welcome to Mallorca - Immobilien Mallorca Blog\" \/>\n<meta property=\"og:description\" content=\"Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilien Mallorca Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casanova.immobilien.mallorca\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-18T10:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"thilo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Immosantaponsa\" \/>\n<meta name=\"twitter:site\" content=\"@Immosantaponsa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"thilo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/\"},\"author\":{\"name\":\"thilo\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/person\\\/99f6e09a7f4d71aadc0718d9a3957f7a\"},\"headline\":\"Finally back: Welcome to Mallorca\",\"datePublished\":\"2021-03-18T10:56:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header_750-1.jpg\",\"articleSection\":[\"Buy real estate\",\"Mallorca Real Estate\",\"Real estate market Mallorca\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/\",\"name\":\"Finally back: Welcome to Mallorca - Immobilien Mallorca Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header_750-1.jpg\",\"datePublished\":\"2021-03-18T10:56:41+00:00\",\"description\":\"Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header_750-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/header_750-1.jpg\",\"width\":750,\"height\":531,\"caption\":\"Welcome to Mallorca Casa Nova Properties\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/finally-back-welcome-to-mallorca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finally back: Welcome to Mallorca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/\",\"name\":\"Immobilien Mallorca Blog\",\"description\":\"Casa Nova Properties\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#organization\",\"name\":\"Casa Nova Properties S. L.\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/casanovalogo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/casanovalogo-web.png\",\"width\":478,\"height\":152,\"caption\":\"Casa Nova Properties S. L.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casanova.immobilien.mallorca\",\"https:\\\/\\\/x.com\\\/Immosantaponsa\",\"https:\\\/\\\/www.instagram.com\\\/casanovaproperties.mallorca\\\/\",\"http:\\\/\\\/www.pinterest.com\\\/cnpimmobilien\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9PGIa8TcOBJrQEx3uGuLgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/person\\\/99f6e09a7f4d71aadc0718d9a3957f7a\",\"name\":\"thilo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g\",\"caption\":\"thilo\"},\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/author\\\/thilo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finally back: Welcome to Mallorca - Immobilien Mallorca Blog","description":"Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/","og_locale":"en_GB","og_type":"article","og_title":"Finally back: Welcome to Mallorca - Immobilien Mallorca Blog","og_description":"Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures.","og_url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/","og_site_name":"Immobilien Mallorca Blog","article_publisher":"https:\/\/www.facebook.com\/casanova.immobilien.mallorca","article_published_time":"2021-03-18T10:56:41+00:00","og_image":[{"width":750,"height":531,"url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg","type":"image\/jpeg"}],"author":"thilo","twitter_card":"summary_large_image","twitter_creator":"@Immosantaponsa","twitter_site":"@Immosantaponsa","twitter_misc":{"Written by":"thilo","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#article","isPartOf":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/"},"author":{"name":"thilo","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/person\/99f6e09a7f4d71aadc0718d9a3957f7a"},"headline":"Finally back: Welcome to Mallorca","datePublished":"2021-03-18T10:56:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#organization"},"image":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg","articleSection":["Buy real estate","Mallorca Real Estate","Real estate market Mallorca"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/","name":"Finally back: Welcome to Mallorca - Immobilien Mallorca Blog","isPartOf":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#primaryimage"},"image":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg","datePublished":"2021-03-18T10:56:41+00:00","description":"Finally, on 14.3. the travel warning of the German Robert-Koch-Institute for Mallorca was lifted due to the good incidence figures.","breadcrumb":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#primaryimage","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg","contentUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2021\/03\/header_750-1.jpg","width":750,"height":531,"caption":"Welcome to Mallorca Casa Nova Properties"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/finally-back-welcome-to-mallorca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/"},{"@type":"ListItem","position":2,"name":"Finally back: Welcome to Mallorca"}]},{"@type":"WebSite","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#website","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/","name":"Immobilien Mallorca Blog","description":"Casa Nova Properties","publisher":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#organization","name":"Casa Nova Properties S. L.","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2020\/02\/casanovalogo-web.png","contentUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2020\/02\/casanovalogo-web.png","width":478,"height":152,"caption":"Casa Nova Properties S. L."},"image":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casanova.immobilien.mallorca","https:\/\/x.com\/Immosantaponsa","https:\/\/www.instagram.com\/casanovaproperties.mallorca\/","http:\/\/www.pinterest.com\/cnpimmobilien\/","https:\/\/www.youtube.com\/channel\/UC9PGIa8TcOBJrQEx3uGuLgw"]},{"@type":"Person","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/person\/99f6e09a7f4d71aadc0718d9a3957f7a","name":"thilo","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g","caption":"thilo"},"url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/author\/thilo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/posts\/7754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/comments?post=7754"}],"version-history":[{"count":0,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/posts\/7754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/media\/7757"}],"wp:attachment":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/media?parent=7754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/categories?post=7754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/tags?post=7754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}