{"id":8124,"date":"2023-10-11T08:06:51","date_gmt":"2023-10-11T08:06:51","guid":{"rendered":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/?p=8124"},"modified":"2023-10-11T08:06:51","modified_gmt":"2023-10-11T08:06:51","slug":"our-competent-team","status":"publish","type":"post","link":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/","title":{"rendered":"Our competent team"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8125\" src=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg\" alt=\"Casa Nova Properties - our competent team\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg 750w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750-330x220.jpg 330w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750-624x416.jpg 624w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>Casa Nova Properties &#8211; our competent team<\/h2>\n<p>Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation between all parties of the contract. <!--more-->On the one hand the prospective buyer, who would like to acquire his personal dream property on Mallorca. And on the other hand, the seller, who wants to achieve a fair market sales price for his property.<\/p>\n<p>Our most important task is to do justice to both sides so that a final notary appointment can be made.<br \/>\nOnly if both parties are ultimately satisfied, we have done our job well!<\/p>\n<p>This is our highest goal!<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8126\" src=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/footer_750.jpg\" alt=\"\" width=\"750\" height=\"424\" srcset=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/footer_750.jpg 750w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/footer_750-330x187.jpg 330w, https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/footer_750-736x416.jpg 736w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casa Nova Properties &#8211; our competent team Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation between all parties of the contract.<\/p>\n","protected":false},"author":2,"featured_media":8125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-without_assignment"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our competent team - Immobilien Mallorca Blog<\/title>\n<meta name=\"description\" content=\"Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our competent team - Immobilien Mallorca Blog\" \/>\n<meta property=\"og:description\" content=\"Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilien Mallorca Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casanova.immobilien.mallorca\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-11T08:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"thilo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Immosantaponsa\" \/>\n<meta name=\"twitter:site\" content=\"@Immosantaponsa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"thilo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/\"},\"author\":{\"name\":\"thilo\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/person\\\/99f6e09a7f4d71aadc0718d9a3957f7a\"},\"headline\":\"Our competent team\",\"datePublished\":\"2023-10-11T08:06:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/\"},\"wordCount\":114,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/header_750.jpg\",\"articleSection\":[\"without assignment\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/\",\"name\":\"Our competent team - Immobilien Mallorca Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/header_750.jpg\",\"datePublished\":\"2023-10-11T08:06:51+00:00\",\"description\":\"Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/header_750.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/header_750.jpg\",\"width\":750,\"height\":500,\"caption\":\"Casa Nova Properties - our competent team\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/our-competent-team\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our competent team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/\",\"name\":\"Immobilien Mallorca Blog\",\"description\":\"Casa Nova Properties\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#organization\",\"name\":\"Casa Nova Properties S. L.\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/casanovalogo-web.png\",\"contentUrl\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/casanovalogo-web.png\",\"width\":478,\"height\":152,\"caption\":\"Casa Nova Properties S. L.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/casanova.immobilien.mallorca\",\"https:\\\/\\\/x.com\\\/Immosantaponsa\",\"https:\\\/\\\/www.instagram.com\\\/casanovaproperties.mallorca\\\/\",\"http:\\\/\\\/www.pinterest.com\\\/cnpimmobilien\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9PGIa8TcOBJrQEx3uGuLgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/#\\\/schema\\\/person\\\/99f6e09a7f4d71aadc0718d9a3957f7a\",\"name\":\"thilo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g\",\"caption\":\"thilo\"},\"url\":\"https:\\\/\\\/www.mallorcaimmobilien.com\\\/blog\\\/en\\\/author\\\/thilo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our competent team - Immobilien Mallorca Blog","description":"Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/","og_locale":"en_GB","og_type":"article","og_title":"Our competent team - Immobilien Mallorca Blog","og_description":"Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation.","og_url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/","og_site_name":"Immobilien Mallorca Blog","article_publisher":"https:\/\/www.facebook.com\/casanova.immobilien.mallorca","article_published_time":"2023-10-11T08:06:51+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg","type":"image\/jpeg"}],"author":"thilo","twitter_card":"summary_large_image","twitter_creator":"@Immosantaponsa","twitter_site":"@Immosantaponsa","twitter_misc":{"Written by":"thilo","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#article","isPartOf":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/"},"author":{"name":"thilo","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/person\/99f6e09a7f4d71aadc0718d9a3957f7a"},"headline":"Our competent team","datePublished":"2023-10-11T08:06:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/"},"wordCount":114,"commentCount":0,"publisher":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#organization"},"image":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg","articleSection":["without assignment"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/","name":"Our competent team - Immobilien Mallorca Blog","isPartOf":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#primaryimage"},"image":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg","datePublished":"2023-10-11T08:06:51+00:00","description":"Our many years of business success as a real estate agent in the southwest of Mallorca is based on a trusting cooperation.","breadcrumb":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#primaryimage","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg","contentUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2023\/10\/header_750.jpg","width":750,"height":500,"caption":"Casa Nova Properties - our competent team"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/our-competent-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/"},{"@type":"ListItem","position":2,"name":"Our competent team"}]},{"@type":"WebSite","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#website","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/","name":"Immobilien Mallorca Blog","description":"Casa Nova Properties","publisher":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#organization","name":"Casa Nova Properties S. L.","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2020\/02\/casanovalogo-web.png","contentUrl":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-content\/uploads\/2020\/02\/casanovalogo-web.png","width":478,"height":152,"caption":"Casa Nova Properties S. L."},"image":{"@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casanova.immobilien.mallorca","https:\/\/x.com\/Immosantaponsa","https:\/\/www.instagram.com\/casanovaproperties.mallorca\/","http:\/\/www.pinterest.com\/cnpimmobilien\/","https:\/\/www.youtube.com\/channel\/UC9PGIa8TcOBJrQEx3uGuLgw"]},{"@type":"Person","@id":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/#\/schema\/person\/99f6e09a7f4d71aadc0718d9a3957f7a","name":"thilo","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/982895c38c8bf94426d2459144e22e3bc4431a4ad16e74d9852dd4632fd9dc50?s=96&d=mm&r=g","caption":"thilo"},"url":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/author\/thilo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/posts\/8124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/comments?post=8124"}],"version-history":[{"count":0,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/posts\/8124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/media\/8125"}],"wp:attachment":[{"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/media?parent=8124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/categories?post=8124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mallorcaimmobilien.com\/blog\/en\/wp-json\/wp\/v2\/tags?post=8124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}